{"id":31897,"date":"2021-06-30T17:55:33","date_gmt":"2021-06-30T17:55:33","guid":{"rendered":"https:\/\/usapulseseu.org\/saute-de-pois-chiches-aux-champignons\/"},"modified":"2021-06-30T17:55:33","modified_gmt":"2021-06-30T17:55:33","slug":"saute-de-pois-chiches-aux-champignons","status":"publish","type":"post","link":"https:\/\/usapulseseu.org\/fr\/saute-de-pois-chiches-aux-champignons\/","title":{"rendered":"SAUT\u00c9 DE POIS CHICHES AUX CHAMPIGNONS"},"content":{"rendered":"<p><!--WPRM Recipe 9415--><\/p>\n<div class=\"wprm-fallback-recipe\">\n<h2 class=\"wprm-fallback-recipe-name\">SAUT\u00c9 DE POIS CHICHES AUX CHAMPIGNONS<\/h2>\n<p>\t<img decoding=\"async\" class=\"wprm-fallback-recipe-image\" src=\"https:\/\/usapulseseu.org\/wp-content\/uploads\/2021\/06\/Salteado-de-garbanzos-con-setas-150x150.jpg\">\t<\/p>\n<p class=\"wprm-fallback-recipe-summary\">\n<div class=\"wprm-fallback-recipe-equipment\">\n\t\t\t<\/div>\n<div class=\"wprm-fallback-recipe-ingredients\">\n<ul>\n<li>400 g de pois chiches<\/li>\n<li>350 g de champignons (diff\u00e9rents types)<\/li>\n<li>200 g d&rsquo;oignon hach\u00e9<\/li>\n<li>200 g de tomates cerises<\/li>\n<li>4 cuill\u00e8res \u00e0 soupe d&rsquo;huile d&rsquo;olive<\/li>\n<li>\u00bd cuill\u00e8re \u00e0 caf\u00e9 de thym<\/li>\n<li>Sel<\/li>\n<li>Pepp<\/li>\n<\/ul><\/div>\n<div class=\"wprm-fallback-recipe-instructions\">\n<ol>\n<li>Dans une casserole, faites chauffer l&rsquo;huile, ajoutez l&rsquo;oignon et faites-le revenir jusqu&rsquo;\u00e0 ce qu&rsquo;il devienne transparent. Ajoutez les champignons, les gros cubes et les tomates cerises coup\u00e9es en deux. Faites sauter pendant environ cinq minutes, ajoutez les pois chiches et le thym. Assaisonnez avec du sel et du poivre.   <\/li>\n<li>Couvrez et laissez mijoter dans son jus pendant encore cinq minutes.<\/li>\n<li>Servir chaud.<\/li>\n<\/ol><\/div>\n<div class=\"wprm-fallback-recipe-notes\">\n\t\t\t<\/div>\n<div class=\"wprm-fallback-recipe-meta\">\n<div class=\"wprm-fallback-recipe-meta-course\">Plat principal<\/div>\n<div class=\"wprm-fallback-recipe-meta-keyword\">Sans gluten, traditionnel, v\u00e9g\u00e9talien<\/div>\n<\/p><\/div>\n<\/div>\n<p><!--End WPRM Recipe--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>SAUT\u00c9 DE POIS CHICHES AUX CHAMPIGNONS 400 g de pois chiches 350 g de champignons (diff\u00e9rents types) 200 g d&rsquo;oignon hach\u00e9 200 g de tomates cerises 4 cuill\u00e8res \u00e0 soupe d&rsquo;huile d&rsquo;olive \u00bd cuill\u00e8re \u00e0 caf\u00e9 de thym Sel Pepp Dans une casserole, faites chauffer l&rsquo;huile, ajoutez l&rsquo;oignon et faites-le revenir jusqu&rsquo;\u00e0 ce qu&rsquo;il devienne [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":27537,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[115],"tags":[116,150,113],"dipi_cpt_category":[],"class_list":["post-31897","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-plat-principal","tag-sans-gluten-fr","tag-traditionnel","tag-vegetalien-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SAUT\u00c9 DE POIS CHICHES AUX CHAMPIGNONS - USA Pulses EU<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/usapulseseu.org\/fr\/saute-de-pois-chiches-aux-champignons\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SAUT\u00c9 DE POIS CHICHES AUX CHAMPIGNONS - USA Pulses EU\" \/>\n<meta property=\"og:description\" content=\"SAUT\u00c9 DE POIS CHICHES AUX CHAMPIGNONS 400 g de pois chiches 350 g de champignons (diff\u00e9rents types) 200 g d&rsquo;oignon hach\u00e9 200 g de tomates cerises 4 cuill\u00e8res \u00e0 soupe d&rsquo;huile d&rsquo;olive \u00bd cuill\u00e8re \u00e0 caf\u00e9 de thym Sel Pepp Dans une casserole, faites chauffer l&rsquo;huile, ajoutez l&rsquo;oignon et faites-le revenir jusqu&rsquo;\u00e0 ce qu&rsquo;il devienne [&hellip;]\" \/>\n<meta property=\"og:site_name\" content=\"USA Pulses EU\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/USAPulsesEurope\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-30T17:55:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/usapulseseu.org\/wp-content\/uploads\/2021\/06\/Salteado-de-garbanzos-con-setas.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"360\" \/>\n\t<meta property=\"og:image:height\" content=\"213\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"James Read\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"James Read\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/usapulseseu.org\/fr\/saute-de-pois-chiches-aux-champignons\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/usapulseseu.org\/fr\/saute-de-pois-chiches-aux-champignons\/\"},\"author\":{\"name\":\"James Read\",\"@id\":\"https:\/\/usapulseseu.org\/fr\/#\/schema\/person\/6dca391312a6bf83543db2a8655a0f04\"},\"headline\":\"SAUT\u00c9 DE POIS CHICHES AUX CHAMPIGNONS\",\"datePublished\":\"2021-06-30T17:55:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/usapulseseu.org\/fr\/saute-de-pois-chiches-aux-champignons\/\"},\"wordCount\":118,\"publisher\":{\"@id\":\"https:\/\/usapulseseu.org\/fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/usapulseseu.org\/fr\/saute-de-pois-chiches-aux-champignons\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/usapulseseu.org\/wp-content\/uploads\/2021\/06\/Salteado-de-garbanzos-con-setas.jpg\",\"keywords\":[\"Sans gluten\",\"Traditionnel\",\"V\u00e9g\u00e9talien\"],\"articleSection\":[\"Plat principal\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/usapulseseu.org\/fr\/saute-de-pois-chiches-aux-champignons\/\",\"url\":\"https:\/\/usapulseseu.org\/fr\/saute-de-pois-chiches-aux-champignons\/\",\"name\":\"SAUT\u00c9 DE POIS CHICHES AUX CHAMPIGNONS - USA Pulses EU\",\"isPartOf\":{\"@id\":\"https:\/\/usapulseseu.org\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/usapulseseu.org\/fr\/saute-de-pois-chiches-aux-champignons\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/usapulseseu.org\/fr\/saute-de-pois-chiches-aux-champignons\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/usapulseseu.org\/wp-content\/uploads\/2021\/06\/Salteado-de-garbanzos-con-setas.jpg\",\"datePublished\":\"2021-06-30T17:55:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/usapulseseu.org\/fr\/saute-de-pois-chiches-aux-champignons\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/usapulseseu.org\/fr\/saute-de-pois-chiches-aux-champignons\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/usapulseseu.org\/fr\/saute-de-pois-chiches-aux-champignons\/#primaryimage\",\"url\":\"https:\/\/usapulseseu.org\/wp-content\/uploads\/2021\/06\/Salteado-de-garbanzos-con-setas.jpg\",\"contentUrl\":\"https:\/\/usapulseseu.org\/wp-content\/uploads\/2021\/06\/Salteado-de-garbanzos-con-setas.jpg\",\"width\":360,\"height\":213},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/usapulseseu.org\/fr\/saute-de-pois-chiches-aux-champignons\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/usapulseseu.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SAUT\u00c9 DE POIS CHICHES AUX CHAMPIGNONS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/usapulseseu.org\/fr\/#website\",\"url\":\"https:\/\/usapulseseu.org\/fr\/\",\"name\":\"USA Pulses EU\",\"description\":\"USA Pulses EU is the European home of pulses from the USA\",\"publisher\":{\"@id\":\"https:\/\/usapulseseu.org\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/usapulseseu.org\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/usapulseseu.org\/fr\/#organization\",\"name\":\"USA Pulses EU\",\"url\":\"https:\/\/usapulseseu.org\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/usapulseseu.org\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/usapulseseu.org\/wp-content\/uploads\/2025\/06\/USA-Pulses-Favicon.png\",\"contentUrl\":\"https:\/\/usapulseseu.org\/wp-content\/uploads\/2025\/06\/USA-Pulses-Favicon.png\",\"width\":512,\"height\":512,\"caption\":\"USA Pulses EU\"},\"image\":{\"@id\":\"https:\/\/usapulseseu.org\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/USAPulsesEurope\",\"https:\/\/www.instagram.com\/usapulseseurope\/\",\"https:\/\/www.tiktok.com\/@usapulseseurope\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/usapulseseu.org\/fr\/#\/schema\/person\/6dca391312a6bf83543db2a8655a0f04\",\"name\":\"James Read\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/usapulseseu.org\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8a4cfd935dc181b630238d141f7f41a129b6428cf30da5f9445e178d111e6d77?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8a4cfd935dc181b630238d141f7f41a129b6428cf30da5f9445e178d111e6d77?s=96&d=mm&r=g\",\"caption\":\"James Read\"},\"url\":\"https:\/\/usapulseseu.org\/fr\/author\/james-readweareliquid-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SAUT\u00c9 DE POIS CHICHES AUX CHAMPIGNONS - USA Pulses EU","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/usapulseseu.org\/fr\/saute-de-pois-chiches-aux-champignons\/","og_locale":"fr_FR","og_type":"article","og_title":"SAUT\u00c9 DE POIS CHICHES AUX CHAMPIGNONS - USA Pulses EU","og_description":"SAUT\u00c9 DE POIS CHICHES AUX CHAMPIGNONS 400 g de pois chiches 350 g de champignons (diff\u00e9rents types) 200 g d&rsquo;oignon hach\u00e9 200 g de tomates cerises 4 cuill\u00e8res \u00e0 soupe d&rsquo;huile d&rsquo;olive \u00bd cuill\u00e8re \u00e0 caf\u00e9 de thym Sel Pepp Dans une casserole, faites chauffer l&rsquo;huile, ajoutez l&rsquo;oignon et faites-le revenir jusqu&rsquo;\u00e0 ce qu&rsquo;il devienne [&hellip;]","og_site_name":"USA Pulses EU","article_publisher":"https:\/\/www.facebook.com\/USAPulsesEurope","article_published_time":"2021-06-30T17:55:33+00:00","og_image":[{"width":360,"height":213,"url":"https:\/\/usapulseseu.org\/wp-content\/uploads\/2021\/06\/Salteado-de-garbanzos-con-setas.jpg","type":"image\/jpeg"}],"author":"James Read","twitter_card":"summary_large_image","twitter_misc":{"Written by":"James Read","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/usapulseseu.org\/fr\/saute-de-pois-chiches-aux-champignons\/#article","isPartOf":{"@id":"https:\/\/usapulseseu.org\/fr\/saute-de-pois-chiches-aux-champignons\/"},"author":{"name":"James Read","@id":"https:\/\/usapulseseu.org\/fr\/#\/schema\/person\/6dca391312a6bf83543db2a8655a0f04"},"headline":"SAUT\u00c9 DE POIS CHICHES AUX CHAMPIGNONS","datePublished":"2021-06-30T17:55:33+00:00","mainEntityOfPage":{"@id":"https:\/\/usapulseseu.org\/fr\/saute-de-pois-chiches-aux-champignons\/"},"wordCount":118,"publisher":{"@id":"https:\/\/usapulseseu.org\/fr\/#organization"},"image":{"@id":"https:\/\/usapulseseu.org\/fr\/saute-de-pois-chiches-aux-champignons\/#primaryimage"},"thumbnailUrl":"https:\/\/usapulseseu.org\/wp-content\/uploads\/2021\/06\/Salteado-de-garbanzos-con-setas.jpg","keywords":["Sans gluten","Traditionnel","V\u00e9g\u00e9talien"],"articleSection":["Plat principal"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/usapulseseu.org\/fr\/saute-de-pois-chiches-aux-champignons\/","url":"https:\/\/usapulseseu.org\/fr\/saute-de-pois-chiches-aux-champignons\/","name":"SAUT\u00c9 DE POIS CHICHES AUX CHAMPIGNONS - USA Pulses EU","isPartOf":{"@id":"https:\/\/usapulseseu.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/usapulseseu.org\/fr\/saute-de-pois-chiches-aux-champignons\/#primaryimage"},"image":{"@id":"https:\/\/usapulseseu.org\/fr\/saute-de-pois-chiches-aux-champignons\/#primaryimage"},"thumbnailUrl":"https:\/\/usapulseseu.org\/wp-content\/uploads\/2021\/06\/Salteado-de-garbanzos-con-setas.jpg","datePublished":"2021-06-30T17:55:33+00:00","breadcrumb":{"@id":"https:\/\/usapulseseu.org\/fr\/saute-de-pois-chiches-aux-champignons\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/usapulseseu.org\/fr\/saute-de-pois-chiches-aux-champignons\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/usapulseseu.org\/fr\/saute-de-pois-chiches-aux-champignons\/#primaryimage","url":"https:\/\/usapulseseu.org\/wp-content\/uploads\/2021\/06\/Salteado-de-garbanzos-con-setas.jpg","contentUrl":"https:\/\/usapulseseu.org\/wp-content\/uploads\/2021\/06\/Salteado-de-garbanzos-con-setas.jpg","width":360,"height":213},{"@type":"BreadcrumbList","@id":"https:\/\/usapulseseu.org\/fr\/saute-de-pois-chiches-aux-champignons\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/usapulseseu.org\/"},{"@type":"ListItem","position":2,"name":"SAUT\u00c9 DE POIS CHICHES AUX CHAMPIGNONS"}]},{"@type":"WebSite","@id":"https:\/\/usapulseseu.org\/fr\/#website","url":"https:\/\/usapulseseu.org\/fr\/","name":"USA Pulses EU","description":"USA Pulses EU is the European home of pulses from the USA","publisher":{"@id":"https:\/\/usapulseseu.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/usapulseseu.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/usapulseseu.org\/fr\/#organization","name":"USA Pulses EU","url":"https:\/\/usapulseseu.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/usapulseseu.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/usapulseseu.org\/wp-content\/uploads\/2025\/06\/USA-Pulses-Favicon.png","contentUrl":"https:\/\/usapulseseu.org\/wp-content\/uploads\/2025\/06\/USA-Pulses-Favicon.png","width":512,"height":512,"caption":"USA Pulses EU"},"image":{"@id":"https:\/\/usapulseseu.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/USAPulsesEurope","https:\/\/www.instagram.com\/usapulseseurope\/","https:\/\/www.tiktok.com\/@usapulseseurope"]},{"@type":"Person","@id":"https:\/\/usapulseseu.org\/fr\/#\/schema\/person\/6dca391312a6bf83543db2a8655a0f04","name":"James Read","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/usapulseseu.org\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8a4cfd935dc181b630238d141f7f41a129b6428cf30da5f9445e178d111e6d77?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a4cfd935dc181b630238d141f7f41a129b6428cf30da5f9445e178d111e6d77?s=96&d=mm&r=g","caption":"James Read"},"url":"https:\/\/usapulseseu.org\/fr\/author\/james-readweareliquid-com\/"}]}},"featured_image_src":"https:\/\/usapulseseu.org\/wp-content\/uploads\/2021\/06\/Salteado-de-garbanzos-con-setas.jpg","featured_image_src_square":"https:\/\/usapulseseu.org\/wp-content\/uploads\/2021\/06\/Salteado-de-garbanzos-con-setas.jpg","author_info":{"display_name":"James Read","author_link":"https:\/\/usapulseseu.org\/fr\/author\/james-readweareliquid-com\/"},"_links":{"self":[{"href":"https:\/\/usapulseseu.org\/fr\/wp-json\/wp\/v2\/posts\/31897","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/usapulseseu.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/usapulseseu.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/usapulseseu.org\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/usapulseseu.org\/fr\/wp-json\/wp\/v2\/comments?post=31897"}],"version-history":[{"count":0,"href":"https:\/\/usapulseseu.org\/fr\/wp-json\/wp\/v2\/posts\/31897\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/usapulseseu.org\/fr\/wp-json\/wp\/v2\/media\/27537"}],"wp:attachment":[{"href":"https:\/\/usapulseseu.org\/fr\/wp-json\/wp\/v2\/media?parent=31897"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/usapulseseu.org\/fr\/wp-json\/wp\/v2\/categories?post=31897"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/usapulseseu.org\/fr\/wp-json\/wp\/v2\/tags?post=31897"},{"taxonomy":"dipi_cpt_category","embeddable":true,"href":"https:\/\/usapulseseu.org\/fr\/wp-json\/wp\/v2\/dipi_cpt_category?post=31897"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}