{"id":31574,"date":"2022-08-29T12:54:36","date_gmt":"2022-08-29T12:54:36","guid":{"rendered":"https:\/\/usapulseseu.org\/sopa-de-brocolos-e-feijao-frade\/"},"modified":"2022-08-29T12:54:36","modified_gmt":"2022-08-29T12:54:36","slug":"sopa-de-brocolos-e-feijao-frade","status":"publish","type":"post","link":"https:\/\/usapulseseu.org\/pt-pt\/sopa-de-brocolos-e-feijao-frade\/","title":{"rendered":"Sopa de br\u00f3colos e feij\u00e3o-frade"},"content":{"rendered":"<p><!--WPRM Recipe 20507--><\/p>\n<div class=\"wprm-fallback-recipe\">\n<h2 class=\"wprm-fallback-recipe-name\">Sopa de br\u00f3colos e feij\u00e3o-frade<\/h2>\n<p>\t<img decoding=\"async\" class=\"wprm-fallback-recipe-image\" src=\"https:\/\/usapulseseu.org\/wp-content\/uploads\/2022\/08\/Broccoli-and-kidney-bean-soup-150x150.jpeg\">\t<\/p>\n<p class=\"wprm-fallback-recipe-summary\">\n<div class=\"wprm-fallback-recipe-equipment\">\n\t\t\t<\/div>\n<div class=\"wprm-fallback-recipe-ingredients\">\n<ul>\n<li>500 g de res\u00edduos de br\u00f3colos (talos e folhas)<\/li>\n<li>300 g de feij\u00e3o frade<\/li>\n<li>2 batatas<\/li>\n<li>2 talos de aipo<\/li>\n<li>1 cebola<\/li>\n<li>Sal<\/li>\n<li>Azeite virgem extra<\/li>\n<li>P\u00e3o estragado<\/li>\n<li>Avel\u00e3s<\/li>\n<\/ul><\/div>\n<div class=\"wprm-fallback-recipe-instructions\">\n<ol>\n<li>Descasca e corta a cebola, o aipo e as batatas. Coloca tudo numa panela grande de fundo alto e tempera com uma gota de azeite. <\/li>\n<li>Passados alguns minutos, junta os talos e as folhas de br\u00f3colos picados e o feij\u00e3o redondo, cobre com \u00e1gua quente (ou caldo de legumes) e deixa ferver. Cozinha durante cerca de 20 minutos e depois mistura. <\/li>\n<li>Serve a sopa quente com croutons, avel\u00e3s tostadas e um fio de azeite cru.<\/li>\n<\/ol><\/div>\n<div class=\"wprm-fallback-recipe-notes\">\n<p>Por <a href=\"https:\/\/www.instagram.com\/glicerinia\/?hl=es\" target=\"_blank\" rel=\"noopener\">@Glicerinia<\/a><\/p>\n<\/p><\/div>\n<div class=\"wprm-fallback-recipe-meta\">\n<div class=\"wprm-fallback-recipe-meta-course\">Arranque<\/div>\n<div class=\"wprm-fallback-recipe-meta-keyword\">Criativo, Sem Lactic\u00ednios, Institucional, Vegan<\/div>\n<\/p><\/div>\n<\/div>\n<p><!--End WPRM Recipe--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sopa de br\u00f3colos e feij\u00e3o-frade 500 g de res\u00edduos de br\u00f3colos (talos e folhas) 300 g de feij\u00e3o frade 2 batatas 2 talos de aipo 1 cebola Sal Azeite virgem extra P\u00e3o estragado Avel\u00e3s Descasca e corta a cebola, o aipo e as batatas. Coloca tudo numa panela grande de fundo alto e tempera com [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":29807,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[102],"tags":[105,137,124,103],"dipi_cpt_category":[],"class_list":["post-31574","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arranque","tag-criativo","tag-institucional-pt-pt","tag-sem-leite","tag-vegan-pt-pt"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sopa de br\u00f3colos e feij\u00e3o-frade - USA Pulses EU<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/usapulseseu.org\/pt-pt\/sopa-de-brocolos-e-feijao-frade\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sopa de br\u00f3colos e feij\u00e3o-frade - USA Pulses EU\" \/>\n<meta property=\"og:description\" content=\"Sopa de br\u00f3colos e feij\u00e3o-frade 500 g de res\u00edduos de br\u00f3colos (talos e folhas) 300 g de feij\u00e3o frade 2 batatas 2 talos de aipo 1 cebola Sal Azeite virgem extra P\u00e3o estragado Avel\u00e3s Descasca e corta a cebola, o aipo e as batatas. Coloca tudo numa panela grande de fundo alto e tempera com [&hellip;]\" \/>\n<meta property=\"og:site_name\" content=\"USA Pulses EU\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/USAPulsesEurope\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-29T12:54:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/usapulseseu.org\/wp-content\/uploads\/2022\/08\/Broccoli-and-kidney-bean-soup-scaled-2.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"924\" \/>\n\t<meta property=\"og:image:height\" content=\"1386\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"James Read\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"James Read\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/usapulseseu.org\/pt-pt\/sopa-de-brocolos-e-feijao-frade\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/usapulseseu.org\/pt-pt\/sopa-de-brocolos-e-feijao-frade\/\"},\"author\":{\"name\":\"James Read\",\"@id\":\"https:\/\/usapulseseu.org\/fr\/#\/schema\/person\/6dca391312a6bf83543db2a8655a0f04\"},\"headline\":\"Sopa de br\u00f3colos e feij\u00e3o-frade\",\"datePublished\":\"2022-08-29T12:54:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/usapulseseu.org\/pt-pt\/sopa-de-brocolos-e-feijao-frade\/\"},\"wordCount\":129,\"publisher\":{\"@id\":\"https:\/\/usapulseseu.org\/fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/usapulseseu.org\/pt-pt\/sopa-de-brocolos-e-feijao-frade\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/usapulseseu.org\/wp-content\/uploads\/2022\/08\/Broccoli-and-kidney-bean-soup-scaled-2.jpeg\",\"keywords\":[\"Criativo\",\"Institucional\",\"Sem leite\",\"Vegan\"],\"articleSection\":[\"Arranque\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/usapulseseu.org\/pt-pt\/sopa-de-brocolos-e-feijao-frade\/\",\"url\":\"https:\/\/usapulseseu.org\/pt-pt\/sopa-de-brocolos-e-feijao-frade\/\",\"name\":\"Sopa de br\u00f3colos e feij\u00e3o-frade - USA Pulses EU\",\"isPartOf\":{\"@id\":\"https:\/\/usapulseseu.org\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/usapulseseu.org\/pt-pt\/sopa-de-brocolos-e-feijao-frade\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/usapulseseu.org\/pt-pt\/sopa-de-brocolos-e-feijao-frade\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/usapulseseu.org\/wp-content\/uploads\/2022\/08\/Broccoli-and-kidney-bean-soup-scaled-2.jpeg\",\"datePublished\":\"2022-08-29T12:54:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/usapulseseu.org\/pt-pt\/sopa-de-brocolos-e-feijao-frade\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/usapulseseu.org\/pt-pt\/sopa-de-brocolos-e-feijao-frade\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/usapulseseu.org\/pt-pt\/sopa-de-brocolos-e-feijao-frade\/#primaryimage\",\"url\":\"https:\/\/usapulseseu.org\/wp-content\/uploads\/2022\/08\/Broccoli-and-kidney-bean-soup-scaled-2.jpeg\",\"contentUrl\":\"https:\/\/usapulseseu.org\/wp-content\/uploads\/2022\/08\/Broccoli-and-kidney-bean-soup-scaled-2.jpeg\",\"width\":924,\"height\":1386},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/usapulseseu.org\/pt-pt\/sopa-de-brocolos-e-feijao-frade\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/usapulseseu.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sopa de br\u00f3colos e feij\u00e3o-frade\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/usapulseseu.org\/fr\/#website\",\"url\":\"https:\/\/usapulseseu.org\/fr\/\",\"name\":\"USA Pulses EU\",\"description\":\"USA Pulses EU is the European home of pulses from the USA\",\"publisher\":{\"@id\":\"https:\/\/usapulseseu.org\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/usapulseseu.org\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/usapulseseu.org\/fr\/#organization\",\"name\":\"USA Pulses EU\",\"url\":\"https:\/\/usapulseseu.org\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/usapulseseu.org\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/usapulseseu.org\/wp-content\/uploads\/2025\/06\/USA-Pulses-Favicon.png\",\"contentUrl\":\"https:\/\/usapulseseu.org\/wp-content\/uploads\/2025\/06\/USA-Pulses-Favicon.png\",\"width\":512,\"height\":512,\"caption\":\"USA Pulses EU\"},\"image\":{\"@id\":\"https:\/\/usapulseseu.org\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/USAPulsesEurope\",\"https:\/\/www.instagram.com\/usapulseseurope\/\",\"https:\/\/www.tiktok.com\/@usapulseseurope\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/usapulseseu.org\/fr\/#\/schema\/person\/6dca391312a6bf83543db2a8655a0f04\",\"name\":\"James Read\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/usapulseseu.org\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8a4cfd935dc181b630238d141f7f41a129b6428cf30da5f9445e178d111e6d77?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8a4cfd935dc181b630238d141f7f41a129b6428cf30da5f9445e178d111e6d77?s=96&d=mm&r=g\",\"caption\":\"James Read\"},\"url\":\"https:\/\/usapulseseu.org\/pt-pt\/author\/james-readweareliquid-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sopa de br\u00f3colos e feij\u00e3o-frade - USA Pulses EU","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/usapulseseu.org\/pt-pt\/sopa-de-brocolos-e-feijao-frade\/","og_locale":"pt_PT","og_type":"article","og_title":"Sopa de br\u00f3colos e feij\u00e3o-frade - USA Pulses EU","og_description":"Sopa de br\u00f3colos e feij\u00e3o-frade 500 g de res\u00edduos de br\u00f3colos (talos e folhas) 300 g de feij\u00e3o frade 2 batatas 2 talos de aipo 1 cebola Sal Azeite virgem extra P\u00e3o estragado Avel\u00e3s Descasca e corta a cebola, o aipo e as batatas. Coloca tudo numa panela grande de fundo alto e tempera com [&hellip;]","og_site_name":"USA Pulses EU","article_publisher":"https:\/\/www.facebook.com\/USAPulsesEurope","article_published_time":"2022-08-29T12:54:36+00:00","og_image":[{"width":924,"height":1386,"url":"https:\/\/usapulseseu.org\/wp-content\/uploads\/2022\/08\/Broccoli-and-kidney-bean-soup-scaled-2.jpeg","type":"image\/jpeg"}],"author":"James Read","twitter_card":"summary_large_image","twitter_misc":{"Written by":"James Read","Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/usapulseseu.org\/pt-pt\/sopa-de-brocolos-e-feijao-frade\/#article","isPartOf":{"@id":"https:\/\/usapulseseu.org\/pt-pt\/sopa-de-brocolos-e-feijao-frade\/"},"author":{"name":"James Read","@id":"https:\/\/usapulseseu.org\/fr\/#\/schema\/person\/6dca391312a6bf83543db2a8655a0f04"},"headline":"Sopa de br\u00f3colos e feij\u00e3o-frade","datePublished":"2022-08-29T12:54:36+00:00","mainEntityOfPage":{"@id":"https:\/\/usapulseseu.org\/pt-pt\/sopa-de-brocolos-e-feijao-frade\/"},"wordCount":129,"publisher":{"@id":"https:\/\/usapulseseu.org\/fr\/#organization"},"image":{"@id":"https:\/\/usapulseseu.org\/pt-pt\/sopa-de-brocolos-e-feijao-frade\/#primaryimage"},"thumbnailUrl":"https:\/\/usapulseseu.org\/wp-content\/uploads\/2022\/08\/Broccoli-and-kidney-bean-soup-scaled-2.jpeg","keywords":["Criativo","Institucional","Sem leite","Vegan"],"articleSection":["Arranque"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/usapulseseu.org\/pt-pt\/sopa-de-brocolos-e-feijao-frade\/","url":"https:\/\/usapulseseu.org\/pt-pt\/sopa-de-brocolos-e-feijao-frade\/","name":"Sopa de br\u00f3colos e feij\u00e3o-frade - USA Pulses EU","isPartOf":{"@id":"https:\/\/usapulseseu.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/usapulseseu.org\/pt-pt\/sopa-de-brocolos-e-feijao-frade\/#primaryimage"},"image":{"@id":"https:\/\/usapulseseu.org\/pt-pt\/sopa-de-brocolos-e-feijao-frade\/#primaryimage"},"thumbnailUrl":"https:\/\/usapulseseu.org\/wp-content\/uploads\/2022\/08\/Broccoli-and-kidney-bean-soup-scaled-2.jpeg","datePublished":"2022-08-29T12:54:36+00:00","breadcrumb":{"@id":"https:\/\/usapulseseu.org\/pt-pt\/sopa-de-brocolos-e-feijao-frade\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/usapulseseu.org\/pt-pt\/sopa-de-brocolos-e-feijao-frade\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/usapulseseu.org\/pt-pt\/sopa-de-brocolos-e-feijao-frade\/#primaryimage","url":"https:\/\/usapulseseu.org\/wp-content\/uploads\/2022\/08\/Broccoli-and-kidney-bean-soup-scaled-2.jpeg","contentUrl":"https:\/\/usapulseseu.org\/wp-content\/uploads\/2022\/08\/Broccoli-and-kidney-bean-soup-scaled-2.jpeg","width":924,"height":1386},{"@type":"BreadcrumbList","@id":"https:\/\/usapulseseu.org\/pt-pt\/sopa-de-brocolos-e-feijao-frade\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/usapulseseu.org\/"},{"@type":"ListItem","position":2,"name":"Sopa de br\u00f3colos e feij\u00e3o-frade"}]},{"@type":"WebSite","@id":"https:\/\/usapulseseu.org\/fr\/#website","url":"https:\/\/usapulseseu.org\/fr\/","name":"USA Pulses EU","description":"USA Pulses EU is the European home of pulses from the USA","publisher":{"@id":"https:\/\/usapulseseu.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/usapulseseu.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/usapulseseu.org\/fr\/#organization","name":"USA Pulses EU","url":"https:\/\/usapulseseu.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/usapulseseu.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/usapulseseu.org\/wp-content\/uploads\/2025\/06\/USA-Pulses-Favicon.png","contentUrl":"https:\/\/usapulseseu.org\/wp-content\/uploads\/2025\/06\/USA-Pulses-Favicon.png","width":512,"height":512,"caption":"USA Pulses EU"},"image":{"@id":"https:\/\/usapulseseu.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/USAPulsesEurope","https:\/\/www.instagram.com\/usapulseseurope\/","https:\/\/www.tiktok.com\/@usapulseseurope"]},{"@type":"Person","@id":"https:\/\/usapulseseu.org\/fr\/#\/schema\/person\/6dca391312a6bf83543db2a8655a0f04","name":"James Read","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/usapulseseu.org\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8a4cfd935dc181b630238d141f7f41a129b6428cf30da5f9445e178d111e6d77?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8a4cfd935dc181b630238d141f7f41a129b6428cf30da5f9445e178d111e6d77?s=96&d=mm&r=g","caption":"James Read"},"url":"https:\/\/usapulseseu.org\/pt-pt\/author\/james-readweareliquid-com\/"}]}},"featured_image_src":"https:\/\/usapulseseu.org\/wp-content\/uploads\/2022\/08\/Broccoli-and-kidney-bean-soup-scaled-2-600x400.jpeg","featured_image_src_square":"https:\/\/usapulseseu.org\/wp-content\/uploads\/2022\/08\/Broccoli-and-kidney-bean-soup-scaled-2-600x600.jpeg","author_info":{"display_name":"James Read","author_link":"https:\/\/usapulseseu.org\/pt-pt\/author\/james-readweareliquid-com\/"},"_links":{"self":[{"href":"https:\/\/usapulseseu.org\/pt-pt\/wp-json\/wp\/v2\/posts\/31574","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/usapulseseu.org\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/usapulseseu.org\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/usapulseseu.org\/pt-pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/usapulseseu.org\/pt-pt\/wp-json\/wp\/v2\/comments?post=31574"}],"version-history":[{"count":0,"href":"https:\/\/usapulseseu.org\/pt-pt\/wp-json\/wp\/v2\/posts\/31574\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/usapulseseu.org\/pt-pt\/wp-json\/wp\/v2\/media\/29807"}],"wp:attachment":[{"href":"https:\/\/usapulseseu.org\/pt-pt\/wp-json\/wp\/v2\/media?parent=31574"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/usapulseseu.org\/pt-pt\/wp-json\/wp\/v2\/categories?post=31574"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/usapulseseu.org\/pt-pt\/wp-json\/wp\/v2\/tags?post=31574"},{"taxonomy":"dipi_cpt_category","embeddable":true,"href":"https:\/\/usapulseseu.org\/pt-pt\/wp-json\/wp\/v2\/dipi_cpt_category?post=31574"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}